{"id":2405,"date":"2022-12-28T14:40:13","date_gmt":"2022-12-28T14:40:13","guid":{"rendered":"https:\/\/www.ssm-multiflex.cl\/catalogo\/?post_type=product&#038;p=2405"},"modified":"2022-12-28T14:40:45","modified_gmt":"2022-12-28T14:40:45","slug":"fjx-6-6-a-90-2","status":"publish","type":"product","link":"https:\/\/www.ssm-multiflex.cl\/catalogo\/product\/fjx-6-6-a-90-2\/","title":{"rendered":"FJX 6-6 A 90\u00b0"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2406,"template":"","meta":[],"class_list":["post-2405","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-conexiones","product_cat-cuello-largo-a-90","product_cat-fjx"],"_links":{"self":[{"href":"https:\/\/www.ssm-multiflex.cl\/catalogo\/wp-json\/wp\/v2\/product\/2405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ssm-multiflex.cl\/catalogo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ssm-multiflex.cl\/catalogo\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ssm-multiflex.cl\/catalogo\/wp-json\/wp\/v2\/media\/2406"}],"wp:attachment":[{"href":"https:\/\/www.ssm-multiflex.cl\/catalogo\/wp-json\/wp\/v2\/media?parent=2405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}